{"id":1958770,"date":"2026-07-02T00:17:39","date_gmt":"2026-07-02T00:17:39","guid":{"rendered":"https:\/\/culture.ixelles.be\/events\/federico-colli-2\/"},"modified":"2026-07-02T00:17:39","modified_gmt":"2026-07-02T00:17:39","slug":"federico-colli-2","status":"publish","type":"events","link":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/","title":{"rendered":"Federico Colli"},"content":{"rendered":"<p>More information soon&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>More information soon&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1958771,"comment_status":"","ping_status":"closed","template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Federico Colli - Ixelles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federico Colli - Ixelles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ixelles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/\",\"url\":\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/\",\"name\":\"Federico Colli - Ixelles\",\"isPartOf\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/07\/1782880383228-d9f8a69097f897ff0aace81a8939a3f578390498.jpg\",\"datePublished\":\"2026-07-02T00:17:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#primaryimage\",\"url\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/07\/1782880383228-d9f8a69097f897ff0aace81a8939a3f578390498.jpg\",\"contentUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/07\/1782880383228-d9f8a69097f897ff0aace81a8939a3f578390498.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/culture.ixelles.be\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/culture.ixelles.be\/en\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Federico Colli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/#website\",\"url\":\"https:\/\/culture.ixelles.be\/en\/\",\"name\":\"Ixelles\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/culture.ixelles.be\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/#organization\",\"name\":\"Service culture Ixelles\",\"url\":\"https:\/\/culture.ixelles.be\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg\",\"contentUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg\",\"width\":1,\"height\":1,\"caption\":\"Service culture Ixelles\"},\"image\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Federico Colli - Ixelles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/","og_locale":"en_US","og_type":"article","og_title":"Federico Colli - Ixelles","og_url":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/","og_site_name":"Ixelles","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/","url":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/","name":"Federico Colli - Ixelles","isPartOf":{"@id":"https:\/\/culture.ixelles.be\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#primaryimage"},"image":{"@id":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#primaryimage"},"thumbnailUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/07\/1782880383228-d9f8a69097f897ff0aace81a8939a3f578390498.jpg","datePublished":"2026-07-02T00:17:39+00:00","breadcrumb":{"@id":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#primaryimage","url":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/07\/1782880383228-d9f8a69097f897ff0aace81a8939a3f578390498.jpg","contentUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/07\/1782880383228-d9f8a69097f897ff0aace81a8939a3f578390498.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/culture.ixelles.be\/en\/events\/federico-colli-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/culture.ixelles.be\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/culture.ixelles.be\/en\/events\/"},{"@type":"ListItem","position":3,"name":"Federico Colli"}]},{"@type":"WebSite","@id":"https:\/\/culture.ixelles.be\/en\/#website","url":"https:\/\/culture.ixelles.be\/en\/","name":"Ixelles","description":"","publisher":{"@id":"https:\/\/culture.ixelles.be\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/culture.ixelles.be\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/culture.ixelles.be\/en\/#organization","name":"Service culture Ixelles","url":"https:\/\/culture.ixelles.be\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/culture.ixelles.be\/en\/#\/schema\/logo\/image\/","url":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg","contentUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg","width":1,"height":1,"caption":"Service culture Ixelles"},"image":{"@id":"https:\/\/culture.ixelles.be\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/events\/1958770"}],"collection":[{"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/types\/events"}],"author":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/comments?post=1958770"}],"version-history":[{"count":0,"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/events\/1958770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/media\/1958771"}],"wp:attachment":[{"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/media?parent=1958770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}