{"id":1989729,"date":"2026-09-01T23:13:43","date_gmt":"2026-09-01T23:13:43","guid":{"rendered":"https:\/\/culture.ixelles.be\/events\/cellule-de-crise-2\/"},"modified":"2026-09-01T23:13:43","modified_gmt":"2026-09-01T23:13:43","slug":"cellule-de-crise-2","status":"publish","type":"events","link":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/","title":{"rendered":"Cellule de Crise"},"content":{"rendered":"<p>THRILLER D\u2019UNE MORT POLITICO-M\u00c9DIATIQUEMyriam Leroy continue de r\u00e9gner en son domaine, celui de l\u2019\u00e9gratignage des peaux dures du sexisme contemporain. Son huis clos, ovationn\u00e9 lors de sa premi\u00e8re incursion, revient appuyer l\u00e0 o\u00f9 \u00e7a fait mal.Un ministre, sa cheffe de cabinet et une communicante sp\u00e9cialis\u00e9e dans les situations de crise sont r\u00e9uni.es pour r\u00e9diger un communiqu\u00e9 qui \u00e9vitera le scandale. Harc\u00e8lement moral ? Sexuel ? Personne ne sait exactement (pas m\u00eame l\u2019homme politique qui fait gr\u00e8ve du souvenir). Mais la rumeur court, un journal s\u2019appr\u00eate \u00e0 l\u00e2cher une bombe et le ministre, lui, craint d\u2019\u00eatre cancelled.Tout est question d\u2019image, de timing, d\u2019ego sous tension. Et de sueurs froides sous les costards. On navigue entre strat\u00e9gie de d\u00e9fense et naufrage en direct. C\u2019est dr\u00f4le, cruel, haletant comme un \u00e9pisode de The Morning Show.De Myriam LeroyMise en sc\u00e8ne Morena Prats\u00a0Avec Thibaut N\u00e8ve, Ariane Rousseau et St\u00e9phanie Van Vyve\u00a0Sc\u00e9nographie Sa\u00efd Abitar\u00a0Cr\u00e9ation lumi\u00e8res Guillaume Toussaint Fromentin\u00a0Costumes Sa\u00efd Abitar et Morena Prats\u00a0Production Th\u00e9\u00e2tre de la Toison d\u2019Or\u00a9 Photo\u00a0Lou VerschuerenAvec le soutien du Tax Shelter de Gouvernement F\u00e9d\u00e9ral Belge &#8211; Casa Kafka Pictures<\/p>\n","protected":false},"excerpt":{"rendered":"<p>THRILLER D\u2019UNE MORT POLITICO-M\u00c9DIATIQUEMyriam Leroy continue de r\u00e9gner en son domaine, celui de l\u2019\u00e9gratignage des peaux dures du sexisme contemporain. Son huis clos, ovationn\u00e9 lors de sa premi\u00e8re incursion, revient appuyer l\u00e0 o\u00f9 \u00e7a fait mal.Un ministre, sa cheffe de cabinet et une communicante sp\u00e9cialis\u00e9e dans les situations de crise sont r\u00e9uni.es pour r\u00e9diger un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1989730,"comment_status":"","ping_status":"closed","template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cellule de Crise - Ixelles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cellule de Crise - Ixelles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ixelles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/\",\"url\":\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/\",\"name\":\"Cellule de Crise - Ixelles\",\"isPartOf\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/1788237070344-d2f843d4441116a773f037ed0e8d0f71c71233d1.jpg\",\"datePublished\":\"2026-09-01T23:13:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#primaryimage\",\"url\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/1788237070344-d2f843d4441116a773f037ed0e8d0f71c71233d1.jpg\",\"contentUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/1788237070344-d2f843d4441116a773f037ed0e8d0f71c71233d1.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/culture.ixelles.be\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/culture.ixelles.be\/en\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cellule de Crise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/#website\",\"url\":\"https:\/\/culture.ixelles.be\/en\/\",\"name\":\"Ixelles\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/culture.ixelles.be\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/#organization\",\"name\":\"Service culture Ixelles\",\"url\":\"https:\/\/culture.ixelles.be\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/culture.ixelles.be\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg\",\"contentUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg\",\"width\":1,\"height\":1,\"caption\":\"Service culture Ixelles\"},\"image\":{\"@id\":\"https:\/\/culture.ixelles.be\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cellule de Crise - Ixelles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/","og_locale":"en_US","og_type":"article","og_title":"Cellule de Crise - Ixelles","og_url":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/","og_site_name":"Ixelles","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/","url":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/","name":"Cellule de Crise - Ixelles","isPartOf":{"@id":"https:\/\/culture.ixelles.be\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#primaryimage"},"image":{"@id":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#primaryimage"},"thumbnailUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/1788237070344-d2f843d4441116a773f037ed0e8d0f71c71233d1.jpg","datePublished":"2026-09-01T23:13:43+00:00","breadcrumb":{"@id":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#primaryimage","url":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/1788237070344-d2f843d4441116a773f037ed0e8d0f71c71233d1.jpg","contentUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/1788237070344-d2f843d4441116a773f037ed0e8d0f71c71233d1.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/culture.ixelles.be\/en\/events\/cellule-de-crise-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/culture.ixelles.be\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/culture.ixelles.be\/en\/events\/"},{"@type":"ListItem","position":3,"name":"Cellule de Crise"}]},{"@type":"WebSite","@id":"https:\/\/culture.ixelles.be\/en\/#website","url":"https:\/\/culture.ixelles.be\/en\/","name":"Ixelles","description":"","publisher":{"@id":"https:\/\/culture.ixelles.be\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/culture.ixelles.be\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/culture.ixelles.be\/en\/#organization","name":"Service culture Ixelles","url":"https:\/\/culture.ixelles.be\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/culture.ixelles.be\/en\/#\/schema\/logo\/image\/","url":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg","contentUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg","width":1,"height":1,"caption":"Service culture Ixelles"},"image":{"@id":"https:\/\/culture.ixelles.be\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/events\/1989729"}],"collection":[{"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/types\/events"}],"author":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/comments?post=1989729"}],"version-history":[{"count":0,"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/events\/1989729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/media\/1989730"}],"wp:attachment":[{"href":"https:\/\/culture.ixelles.be\/en\/wp-json\/wp\/v2\/media?parent=1989729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}