{"id":1989485,"date":"2026-09-01T23:07:51","date_gmt":"2026-09-01T23:07:51","guid":{"rendered":"https:\/\/culture.ixelles.be\/events\/confidences-de-bach-2\/"},"modified":"2026-09-01T23:07:51","modified_gmt":"2026-09-01T23:07:51","slug":"confidences-de-bach-2","status":"publish","type":"events","link":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/","title":{"rendered":"Confidences de Bach"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1989487,"comment_status":"","ping_status":"closed","template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confidences de Bach - Ixelles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confidences de Bach - Ixelles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ixelles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/\",\"url\":\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/\",\"name\":\"Confidences de Bach - Ixelles\",\"isPartOf\":{\"@id\":\"https:\/\/culture.ixelles.be\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/cc63ada9e883c1dd2d8686337e637d1f4370182a.png\",\"datePublished\":\"2026-09-01T23:07:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#primaryimage\",\"url\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/cc63ada9e883c1dd2d8686337e637d1f4370182a.png\",\"contentUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/cc63ada9e883c1dd2d8686337e637d1f4370182a.png\",\"width\":1414,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/culture.ixelles.be\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/culture.ixelles.be\/nl\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Confidences de Bach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/culture.ixelles.be\/nl\/#website\",\"url\":\"https:\/\/culture.ixelles.be\/nl\/\",\"name\":\"Ixelles\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/culture.ixelles.be\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/culture.ixelles.be\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/culture.ixelles.be\/nl\/#organization\",\"name\":\"Service culture Ixelles\",\"url\":\"https:\/\/culture.ixelles.be\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/culture.ixelles.be\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg\",\"contentUrl\":\"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg\",\"width\":1,\"height\":1,\"caption\":\"Service culture Ixelles\"},\"image\":{\"@id\":\"https:\/\/culture.ixelles.be\/nl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confidences de Bach - Ixelles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Confidences de Bach - Ixelles","og_url":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/","og_site_name":"Ixelles","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/","url":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/","name":"Confidences de Bach - Ixelles","isPartOf":{"@id":"https:\/\/culture.ixelles.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#primaryimage"},"image":{"@id":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#primaryimage"},"thumbnailUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/cc63ada9e883c1dd2d8686337e637d1f4370182a.png","datePublished":"2026-09-01T23:07:51+00:00","breadcrumb":{"@id":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#primaryimage","url":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/cc63ada9e883c1dd2d8686337e637d1f4370182a.png","contentUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2026\/09\/cc63ada9e883c1dd2d8686337e637d1f4370182a.png","width":1414,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/culture.ixelles.be\/nl\/events\/confidences-de-bach-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/culture.ixelles.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/culture.ixelles.be\/nl\/events\/"},{"@type":"ListItem","position":3,"name":"Confidences de Bach"}]},{"@type":"WebSite","@id":"https:\/\/culture.ixelles.be\/nl\/#website","url":"https:\/\/culture.ixelles.be\/nl\/","name":"Ixelles","description":"","publisher":{"@id":"https:\/\/culture.ixelles.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/culture.ixelles.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/culture.ixelles.be\/nl\/#organization","name":"Service culture Ixelles","url":"https:\/\/culture.ixelles.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/culture.ixelles.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg","contentUrl":"https:\/\/culture.ixelles.be\/wp-content\/uploads\/2021\/05\/ixelles_green.svg","width":1,"height":1,"caption":"Service culture Ixelles"},"image":{"@id":"https:\/\/culture.ixelles.be\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/culture.ixelles.be\/nl\/wp-json\/wp\/v2\/events\/1989485"}],"collection":[{"href":"https:\/\/culture.ixelles.be\/nl\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/culture.ixelles.be\/nl\/wp-json\/wp\/v2\/types\/events"}],"author":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/nl\/wp-json\/wp\/v2\/comments?post=1989485"}],"version-history":[{"count":0,"href":"https:\/\/culture.ixelles.be\/nl\/wp-json\/wp\/v2\/events\/1989485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/culture.ixelles.be\/nl\/wp-json\/wp\/v2\/media\/1989487"}],"wp:attachment":[{"href":"https:\/\/culture.ixelles.be\/nl\/wp-json\/wp\/v2\/media?parent=1989485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}